{"id":3934,"date":"2020-10-22T10:00:36","date_gmt":"2020-10-22T10:00:36","guid":{"rendered":"https:\/\/alan.ch\/?p=3934"},"modified":"2026-04-09T10:54:51","modified_gmt":"2026-04-09T10:54:51","slug":"un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2","status":"publish","type":"post","link":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/","title":{"rendered":"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb139.3%\u00a0\u00bb custom_margin=\u00a0\u00bb|-55px||||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb|1px||10px|false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb|0px||10px|false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width_tablet=\u00a0\u00bb90%\u00a0\u00bb width_phone=\u00a0\u00bb100%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_margin=\u00a0\u00bb|37px||30px|false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb|0px||30px|false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|-120px||0px|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb|42px|||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb min_height=\u00a0\u00bb60.8px\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_0 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_0 et_pb_text_align_left et_pb_bg_layout_light\">\n<h1>Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales<\/h1>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_post_title title=\u00a0\u00bboff\u00a0\u00bb author=\u00a0\u00bboff\u00a0\u00bb date_format=\u00a0\u00bbd. M Y\u00a0\u00bb comments=\u00a0\u00bboff\u00a0\u00bb featured_image=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb meta_text_color=\u00a0\u00bb#009F4A\u00a0\u00bb custom_margin=\u00a0\u00bb||-1px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_post_title][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_margin=\u00a0\u00bb50px||70px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div data-contents=\"true\">\n<div class=\"\" data-block=\"true\" data-editor=\"2lsqv\" data-offset-key=\"28gv5-0-0\">\n<div data-offset-key=\"28gv5-0-0\" class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\">\n<p>Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG.<\/p>\n<p>Face \u00e0 une fusion de notaires, deux philosophies et deux solutions logicielles ont d\u00fb \u00eatre r\u00e9unies en une seule. Florian Schneider nous raconte tout de suite lui-m\u00eame comment cet exercice a \u00e9t\u00e9 r\u00e9ussi.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbFSP Notare AG Droit de la famille Droit des partenariats Droit des successions\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb custom_margin=\u00a0\u00bb20px||60px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb99px||60px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||3px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div data-contents=\"true\">\n<p><em><strong>Monsieur Schneider, la soci\u00e9t\u00e9 FSP Notare AG est une jeune entreprise issue de la fusion de deux \u00e9tudes de notaires bien \u00e9tablies, n&rsquo;est-ce pas ?<\/strong><\/em><\/p>\n<p>Florian Schneider : Exactement. En octobre 2017, l&rsquo;\u00e9tude de notaires H\u00e4nggli + Schneider AG, fond\u00e9e en 1961, a fusionn\u00e9 avec l&rsquo;\u00e9tude de notaires Kl\u00f6ti, qui existait depuis 1973, pour devenir FSP Notare AG. Nous pouvons ainsi exploiter de pr\u00e9cieuses synergies. Parall\u00e8lement, nous sommes pass\u00e9s \u00e0 14 collaborateurs.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>L&rsquo;introduction d&rsquo;ALAN est-elle li\u00e9e \u00e0 cette fusion ?<\/em><\/strong><\/p>\n<p>Florian Schneider : Il se trouve que ALAN Software AG nous a contact\u00e9s juste au bon moment pour nous pr\u00e9senter son logiciel pour cabinets d&rsquo;avocats. Le programme n&rsquo;est pas encore tr\u00e8s connu en Argovie. Mais \u00e9tant donn\u00e9 que nous devions concilier deux philosophies notariales et deux univers logiciels, un produit tiers nous convenait parfaitement. D&rsquo;autant plus que nous avons tout de suite \u00e9t\u00e9 convaincus qu&rsquo;ALAN avait la flexibilit\u00e9 n\u00e9cessaire pour s&rsquo;adapter \u00e0 nos besoins. Nous avons pu apporter nos connaissances pratiques pour le d\u00e9veloppement ult\u00e9rieur, notamment en ce qui concerne le g\u00e9n\u00e9rateur de documents suppl\u00e9mentaire utilis\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Racontez !<\/em><\/strong><\/p>\n<p>Florian Schneider : De nombreux offices notariaux utilisent des documents existants pour un document, comme un contrat de vente, et les \u00e9crasent. Mais il y a beaucoup moins de risques d&rsquo;erreurs si l&rsquo;on dispose d&rsquo;un mod\u00e8le pour cela. Les donn\u00e9es sont en effet disponibles dans la base de donn\u00e9es d&rsquo;ALAN. Le g\u00e9n\u00e9rateur de texte les r\u00e9cup\u00e8re et ins\u00e8re automatiquement les bonnes donn\u00e9es au bon endroit : Ici le prix, l\u00e0 l&rsquo;acheteur, ici le vendeur, bien s\u00fbr toujours grammaticalement correct. Cela se fait en quelques clics et le programme g\u00e9n\u00e8re un texte pr\u00eat \u00e0 l&#8217;emploi, qui est ensuite disponible pour les documents suivants. Il n&rsquo;y a pas de travail r\u00e9p\u00e9titif &#8211; \u00e0 nouveau sujet aux erreurs -, on peut se concentrer sur l&rsquo;essentiel et travailler efficacement.<o:p><\/o:p><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Cela existait-il d\u00e9j\u00e0 sous une forme qui vous servait ?<\/em><\/strong><\/p>\n<p>Florian Schneider : Pas tout \u00e0 fait. Nous avons aid\u00e9 \u00e0 faire \u00e9voluer les choses gr\u00e2ce \u00e0 nos id\u00e9es pr\u00e9cises et \u00e0 notre exp\u00e9rience. Ces adaptations ont sans doute \u00e9t\u00e9 demand\u00e9es \u00e0 ALAN Software AG. Mais l&rsquo;\u00e9quipe s&rsquo;est montr\u00e9e \u00e0 tout moment ouverte \u00e0 nos id\u00e9es et a travaill\u00e9 de mani\u00e8re extr\u00eamement orient\u00e9e vers la recherche de solutions.<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>L&rsquo;introduction s&rsquo;est donc d\u00e9roul\u00e9e sans probl\u00e8me ?<\/strong><\/em><\/p>\n<p>Le d\u00e9fi consistait \u00e0 migrer les donn\u00e9es de deux programmes notariaux diff\u00e9rents et nous avions \u00e9galement des clients communs, il y avait donc un risque de doublons. Apr\u00e8s l&rsquo;installation d&rsquo;ALAN d\u00e9but avril 2018, nous avons d&rsquo;abord migr\u00e9 les donn\u00e9es d&rsquo;un programme, puis celles du second d\u00e9but juillet. Dans l&rsquo;intervalle, nos collaborateurs ont d\u00fb travailler avec deux logiciels en parall\u00e8le. Petit \u00e0 petit, nous avons \u00e9galement cr\u00e9\u00e9 des mod\u00e8les pour le g\u00e9n\u00e9rateur de documents. Nous travaillons d\u00e9sormais de mani\u00e8re uniforme, avec un seul logiciel et un seul g\u00e9n\u00e9rateur, depuis f\u00e9vrier 2020.    <\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Alors, le chemin a \u00e9t\u00e9 long pour vous ?<\/em><\/strong><\/p>\n<p>Florian Schneider : Ce qui a surtout pris du temps, c&rsquo;est de mettre en place les mod\u00e8les de documents selon nos id\u00e9es. Mais ce tr\u00e8s gros travail en vaut extr\u00eamement la peine, je ne peux que conseiller \u00e0 chaque coll\u00e8gue notaire de prendre ce temps. Ensuite, on travaille de mani\u00e8re super efficace !<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Les modules \u00ab\u00a0normaux\u00a0\u00bb d&rsquo;ALAN \u00ab\u00a0GEBU\u00a0\u00bb, \u00ab\u00a0FIBU\u00a0\u00bb et \u00ab\u00a0KRED\u00a0\u00bb sont-ils \u00e9galement efficaces ?<\/em><\/strong><\/p>\n<p>Florian Schneider : Absolument, oui. C&rsquo;est tr\u00e8s agr\u00e9able d&rsquo;avoir la saisie des prestations et la comptabilit\u00e9 dans un seul syst\u00e8me. On peut importer des ordres d&rsquo;e-banking ou saisir par exemple des travaux commenc\u00e9s pendant la fin de l&rsquo;ann\u00e9e, pour ne citer que deux exemples. Tout cela se fait tr\u00e8s confortablement.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Vous \u00eates donc satisfait d&rsquo;ALAN ?<\/em><\/strong><\/p>\n<p>Florian Schneider : Plus que cela ! On est vraiment pris au s\u00e9rieux et on cherche des solutions ensemble. ALAN Software AG est tr\u00e8s orient\u00e9 vers le client.  <\/p>\n<p>&nbsp;<\/p>\n<p>Merci beaucoup pour cet entretien !<\/p>\n<\/div>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||8px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|700|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb20px\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb40px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb header_2_font_size=\u00a0\u00bb28px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.6em\u00a0\u00bb min_height=\u00a0\u00bb61.8px\u00a0\u00bb custom_margin=\u00a0\u00bb||30px|||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||0px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||0px|||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||30px||false|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<div class=\"et_pb_column et_pb_column_4_4 et_pb_column_0 et_pb_css_mix_blend_mode_passthrough et-last-child\">\n<div class=\"et_pb_module et_pb_text et_pb_text_0 et_pb_text_align_left et_pb_bg_layout_light\">\n<p><strong>Vente \u00e0 emporter<\/strong><\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1em\u00a0\u00bb custom_margin=\u00a0\u00bb||28px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb30px||50px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<ul>\n<li><strong>Le g\u00e9n\u00e9rateur de documents d&rsquo;ALAN minimise les erreurs, fait gagner du temps et permet aux collaborateurs de se concentrer sur les t\u00e2ches essentielles.<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>ALAN Software AG s&rsquo;est montr\u00e9 ouvert aux adaptations individuelles et a d\u00e9velopp\u00e9 des solutions pratiques en \u00e9troite collaboration avec FSP Notare AG.<\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Malgr\u00e9 le d\u00e9fi que repr\u00e9sentait la migration des donn\u00e9es de deux logiciels diff\u00e9rents, ALAN a pu \u00eatre mis en place avec succ\u00e8s. L&rsquo;uniformisation de tous les processus et mod\u00e8les a permis de travailler de mani\u00e8re beaucoup plus efficace et harmonis\u00e9e. <\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb1.8em\u00a0\u00bb min_height=\u00a0\u00bb89.8px\u00a0\u00bb custom_margin=\u00a0\u00bb||24px||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb50px||60px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<div data-contents=\"true\">\n<div class=\"\" data-block=\"true\" data-editor=\"974th\" data-offset-key=\"e3a7r-0-0\">\n<div data-offset-key=\"e3a7r-0-0\" class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\">\n<p>ALAN est une solution professionnelle compl\u00e8te pour les cabinets d&rsquo;avocats et les \u00e9tudes de notaires.<\/p>\n<p>Nous nous ferons un plaisir de vous conseiller sur toutes les questions relatives \u00e0 la num\u00e9risation de vos donn\u00e9es et processus. Contactez-nous, sans engagement, pour une consultation gratuite. <\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttp:\/\/alansoftware.youcanbook.me\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbDemander un rendez-vous\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb24px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG.<br \/>\nFace \u00e0 une fusion de notaires, deux philosophies et deux solutions logicielles ont d\u00fb \u00eatre fusionn\u00e9es en une seule. Florian Schneider nous raconte tout de suite lui-m\u00eame comment cet exercice a \u00e9t\u00e9 r\u00e9ussi.<\/p>\n","protected":false},"author":2,"featured_media":3963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[148],"tags":[160,161,152,162,157,156,159,163,149,151,153,158,150,155,154],"class_list":["post-3934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoires-de-reussite","tag-amelioration-de-lefficacite-du-cabinet","tag-automatiser-la-facturation","tag-cabinet-davocats","tag-gestion-des-mandats","tag-la-numerisation-dans-le-notariat","tag-legal-tech-suisse","tag-logiciel-alan","tag-logiciel-de-notariat-suisse","tag-logiciel-pour-cabinets-davocats","tag-notariat-numerique","tag-numerisation-du-cabinet-davocats","tag-numerisation-du-notariat","tag-office-notarial","tag-optimisation-des-processus-du-cabinet-davocats","tag-transformation-numerique-du-cabinet-davocats"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales - ALAN Software AG<\/title>\n<meta name=\"description\" content=\"Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG. Une interview honn\u00eate sur le lancement d&#039;ALAN.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales - ALAN Software AG\" \/>\n<meta property=\"og:description\" content=\"Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG. Une interview honn\u00eate sur le lancement d&#039;ALAN.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/\" \/>\n<meta property=\"og:site_name\" content=\"ALAN Software AG\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T10:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T10:54:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ALAN Software AG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ALAN Software AG\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/\"},\"author\":{\"name\":\"ALAN Software AG\",\"@id\":\"https:\\\/\\\/alan.ch\\\/#\\\/schema\\\/person\\\/3fad25f4173d8c765144b6ce870a6a02\"},\"headline\":\"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales\",\"datePublished\":\"2020-10-22T10:00:36+00:00\",\"dateModified\":\"2026-04-09T10:54:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/\"},\"wordCount\":1534,\"publisher\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alan.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Raumlichkeiten_062-scaled.jpg\",\"keywords\":[\"Am\u00e9lioration de l'efficacit\u00e9 du cabinet\",\"Automatiser la facturation\",\"Cabinet d'avocats\",\"Gestion des mandats\",\"La num\u00e9risation dans le notariat\",\"Legal Tech Suisse\",\"Logiciel ALAN\",\"Logiciel de notariat suisse\",\"Logiciel pour cabinets d'avocats\",\"Notariat num\u00e9rique\",\"Num\u00e9risation du cabinet d'avocats\",\"Num\u00e9risation du notariat\",\"Office notarial\",\"Optimisation des processus du cabinet d'avocats\",\"Transformation num\u00e9rique du cabinet d'avocats\"],\"articleSection\":[\"Histoires de r\u00e9ussite\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/\",\"url\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/\",\"name\":\"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales - ALAN Software AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alan.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Raumlichkeiten_062-scaled.jpg\",\"datePublished\":\"2020-10-22T10:00:36+00:00\",\"dateModified\":\"2026-04-09T10:54:51+00:00\",\"description\":\"Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG. Une interview honn\u00eate sur le lancement d'ALAN.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alan.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Raumlichkeiten_062-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/alan.ch\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/Raumlichkeiten_062-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9Photographie Ulrike Kiese, fotostudio brugg baden villigen zurich businessshooting photo de candidature photographes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alan.ch\\\/fr\\\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/alan.ch\\\/fr\\\/accueil-alan\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alan.ch\\\/#website\",\"url\":\"https:\\\/\\\/alan.ch\\\/\",\"name\":\"ALAN Software AG\",\"description\":\"Die LegalTech Kanzleisoftware\",\"publisher\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alan.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alan.ch\\\/#organization\",\"name\":\"ALAN Software AG\",\"url\":\"https:\\\/\\\/alan.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/alan.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alan.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/ALAN-Logo-2.png\",\"contentUrl\":\"https:\\\/\\\/alan.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/ALAN-Logo-2.png\",\"width\":3309,\"height\":1663,\"caption\":\"ALAN Software AG\"},\"image\":{\"@id\":\"https:\\\/\\\/alan.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/alan-software-ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/alan.ch\\\/#\\\/schema\\\/person\\\/3fad25f4173d8c765144b6ce870a6a02\",\"name\":\"ALAN Software AG\",\"url\":\"https:\\\/\\\/alan.ch\\\/fr\\\/author\\\/webmasteralan-ch\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales - ALAN Software AG","description":"Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG. Une interview honn\u00eate sur le lancement d'ALAN.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales - ALAN Software AG","og_description":"Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG. Une interview honn\u00eate sur le lancement d'ALAN.","og_url":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/","og_site_name":"ALAN Software AG","article_published_time":"2020-10-22T10:00:36+00:00","article_modified_time":"2026-04-09T10:54:51+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg","type":"image\/jpeg"}],"author":"ALAN Software AG","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ALAN Software AG","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#article","isPartOf":{"@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/"},"author":{"name":"ALAN Software AG","@id":"https:\/\/alan.ch\/#\/schema\/person\/3fad25f4173d8c765144b6ce870a6a02"},"headline":"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales","datePublished":"2020-10-22T10:00:36+00:00","dateModified":"2026-04-09T10:54:51+00:00","mainEntityOfPage":{"@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/"},"wordCount":1534,"publisher":{"@id":"https:\/\/alan.ch\/#organization"},"image":{"@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#primaryimage"},"thumbnailUrl":"https:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg","keywords":["Am\u00e9lioration de l'efficacit\u00e9 du cabinet","Automatiser la facturation","Cabinet d'avocats","Gestion des mandats","La num\u00e9risation dans le notariat","Legal Tech Suisse","Logiciel ALAN","Logiciel de notariat suisse","Logiciel pour cabinets d'avocats","Notariat num\u00e9rique","Num\u00e9risation du cabinet d'avocats","Num\u00e9risation du notariat","Office notarial","Optimisation des processus du cabinet d'avocats","Transformation num\u00e9rique du cabinet d'avocats"],"articleSection":["Histoires de r\u00e9ussite"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/","url":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/","name":"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales - ALAN Software AG","isPartOf":{"@id":"https:\/\/alan.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#primaryimage"},"image":{"@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#primaryimage"},"thumbnailUrl":"https:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg","datePublished":"2020-10-22T10:00:36+00:00","dateModified":"2026-04-09T10:54:51+00:00","description":"Entretien avec Florian Schneider, directeur g\u00e9n\u00e9ral de la soci\u00e9t\u00e9 argovienne FSP Notare AG. Une interview honn\u00eate sur le lancement d'ALAN.","breadcrumb":{"@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#primaryimage","url":"https:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg","contentUrl":"https:\/\/alan.ch\/wp-content\/uploads\/2020\/05\/Raumlichkeiten_062-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9Photographie Ulrike Kiese, fotostudio brugg baden villigen zurich businessshooting photo de candidature photographes"},{"@type":"BreadcrumbList","@id":"https:\/\/alan.ch\/fr\/un-saut-quantique-entretien-avec-lavocat-et-notaire-lukas-nauer-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/alan.ch\/fr\/accueil-alan\/"},{"@type":"ListItem","position":2,"name":"Le g\u00e9n\u00e9rateur de documents permet de se concentrer sur les activit\u00e9s notariales"}]},{"@type":"WebSite","@id":"https:\/\/alan.ch\/#website","url":"https:\/\/alan.ch\/","name":"ALAN Software AG","description":"Die LegalTech Kanzleisoftware","publisher":{"@id":"https:\/\/alan.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alan.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/alan.ch\/#organization","name":"ALAN Software AG","url":"https:\/\/alan.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/alan.ch\/#\/schema\/logo\/image\/","url":"https:\/\/alan.ch\/wp-content\/uploads\/2023\/06\/ALAN-Logo-2.png","contentUrl":"https:\/\/alan.ch\/wp-content\/uploads\/2023\/06\/ALAN-Logo-2.png","width":3309,"height":1663,"caption":"ALAN Software AG"},"image":{"@id":"https:\/\/alan.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/alan-software-ag\/"]},{"@type":"Person","@id":"https:\/\/alan.ch\/#\/schema\/person\/3fad25f4173d8c765144b6ce870a6a02","name":"ALAN Software AG","url":"https:\/\/alan.ch\/fr\/author\/webmasteralan-ch\/"}]}},"_links":{"self":[{"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/posts\/3934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/comments?post=3934"}],"version-history":[{"count":18,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/posts\/3934\/revisions"}],"predecessor-version":[{"id":4547,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/posts\/3934\/revisions\/4547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/media\/3963"}],"wp:attachment":[{"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/media?parent=3934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/categories?post=3934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alan.ch\/fr\/wp-json\/wp\/v2\/tags?post=3934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}